{"id":97268,"date":"2026-05-05T09:11:50","date_gmt":"2026-05-05T07:11:50","guid":{"rendered":"https:\/\/europe.borealoutdoor.com\/product\/tsunami-low-wmns\/"},"modified":"2026-05-05T09:21:39","modified_gmt":"2026-05-05T07:21:39","slug":"tsunami-low-wmns","status":"publish","type":"product","link":"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/","title":{"rendered":"TSUNAMI LOW WMNS"},"content":{"rendered":"<p>Zapatilla de senderismo con tecnolog\u00eda de trail running. Una sinergia de tecnolog\u00edas,  Tsunami es una zapatilla de actividades m\u00faltiples repleta de caracter\u00edsticas de nuestros zapatillas de senderismo y trail running.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zapatilla de senderismo con tecnolog\u00eda de trail running. Una sinergia de tecnolog\u00edas, Tsunami es una zapatilla de actividades m\u00faltiples repleta de caracter\u00edsticas de nuestros zapatillas de senderismo y trail running.<\/p>\n","protected":false},"featured_media":96794,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1012],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TSUNAMI LOW WMNS - Boreal Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TSUNAMI LOW WMNS - Boreal Europe\" \/>\n<meta property=\"og:description\" content=\"Zapatilla de senderismo con tecnolog\u00eda de trail running. Una sinergia de tecnolog\u00edas, Tsunami es una zapatilla de actividades m\u00faltiples repleta de caracter\u00edsticas de nuestros zapatillas de senderismo y trail running.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/\" \/>\n<meta property=\"og:site_name\" content=\"Boreal Europe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Boreal.official\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T07:21:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europe.borealoutdoor.com\/wp-content\/uploads\/sites\/6\/2026\/05\/31706.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@borealoutdoor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/\",\"url\":\"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/\",\"name\":\"TSUNAMI LOW WMNS - Boreal Europe\",\"isPartOf\":{\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/#website\"},\"datePublished\":\"2026-05-05T07:11:50+00:00\",\"dateModified\":\"2026-05-05T07:21:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/europe.borealoutdoor.com\/es\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TSUNAMI LOW WMNS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/#website\",\"url\":\"https:\/\/europe.borealoutdoor.com\/es\/\",\"name\":\"Boreal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/europe.borealoutdoor.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/#organization\",\"name\":\"Boreal\",\"url\":\"https:\/\/europe.borealoutdoor.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/europe.borealoutdoor.com\/wp-content\/uploads\/sites\/6\/2023\/11\/logo-vertical2.png\",\"contentUrl\":\"https:\/\/europe.borealoutdoor.com\/wp-content\/uploads\/sites\/6\/2023\/11\/logo-vertical2.png\",\"width\":257,\"height\":168,\"caption\":\"Boreal\"},\"image\":{\"@id\":\"https:\/\/europe.borealoutdoor.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Boreal.official\/\",\"https:\/\/twitter.com\/borealoutdoor\",\"https:\/\/www.youtube.com\/user\/BorealVideos\",\"https:\/\/www.instagram.com\/borealoutdoor\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TSUNAMI LOW WMNS - Boreal Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/","og_locale":"es_ES","og_type":"article","og_title":"TSUNAMI LOW WMNS - Boreal Europe","og_description":"Zapatilla de senderismo con tecnolog\u00eda de trail running. Una sinergia de tecnolog\u00edas, Tsunami es una zapatilla de actividades m\u00faltiples repleta de caracter\u00edsticas de nuestros zapatillas de senderismo y trail running.","og_url":"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/","og_site_name":"Boreal Europe","article_publisher":"https:\/\/www.facebook.com\/Boreal.official\/","article_modified_time":"2026-05-05T07:21:39+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/europe.borealoutdoor.com\/wp-content\/uploads\/sites\/6\/2026\/05\/31706.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@borealoutdoor","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/","url":"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/","name":"TSUNAMI LOW WMNS - Boreal Europe","isPartOf":{"@id":"https:\/\/europe.borealoutdoor.com\/es\/#website"},"datePublished":"2026-05-05T07:11:50+00:00","dateModified":"2026-05-05T07:21:39+00:00","breadcrumb":{"@id":"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/europe.borealoutdoor.com\/es\/producto\/tsunami-low-wmns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/europe.borealoutdoor.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"TSUNAMI LOW WMNS"}]},{"@type":"WebSite","@id":"https:\/\/europe.borealoutdoor.com\/es\/#website","url":"https:\/\/europe.borealoutdoor.com\/es\/","name":"Boreal","description":"","publisher":{"@id":"https:\/\/europe.borealoutdoor.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europe.borealoutdoor.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/europe.borealoutdoor.com\/es\/#organization","name":"Boreal","url":"https:\/\/europe.borealoutdoor.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/europe.borealoutdoor.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/europe.borealoutdoor.com\/wp-content\/uploads\/sites\/6\/2023\/11\/logo-vertical2.png","contentUrl":"https:\/\/europe.borealoutdoor.com\/wp-content\/uploads\/sites\/6\/2023\/11\/logo-vertical2.png","width":257,"height":168,"caption":"Boreal"},"image":{"@id":"https:\/\/europe.borealoutdoor.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Boreal.official\/","https:\/\/twitter.com\/borealoutdoor","https:\/\/www.youtube.com\/user\/BorealVideos","https:\/\/www.instagram.com\/borealoutdoor\/"]}]}},"_links":{"self":[{"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/product\/97268"}],"collection":[{"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/comments?post=97268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/media\/96794"}],"wp:attachment":[{"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/media?parent=97268"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/product_cat?post=97268"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/europe.borealoutdoor.com\/es\/wp-json\/wp\/v2\/product_tag?post=97268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}